{"id":631,"date":"2020-08-27T12:23:17","date_gmt":"2020-08-27T12:23:17","guid":{"rendered":"https:\/\/ghiti.it\/video\/maman-01-01-dario-zampa\/"},"modified":"2021-03-15T13:42:39","modified_gmt":"2021-03-15T13:42:39","slug":"maman-01-01-dario-zampa","status":"publish","type":"video","link":"https:\/\/ghiti.it\/it\/video\/maman-01-01-dario-zampa\/","title":{"rendered":"DARIO ZAMPA"},"content":{"rendered":"\n<div style=\"text-align: justify;\">\n<p><strong><em>Maman! La trasmissione per bambini tutta in lingua friulana.<\/em><\/strong><strong><em><br>\n<\/em><\/strong>In onda su Telefriuli (canale 11) ogni venerd\u00ec<\/p>\n<p>Una produzione di ARLeF \u2013 Agenzia Regionale per la Lingua Friulana e di Telefriuli<\/p>\n<p>In una casetta dai tanti colori abitano Daria e il gattino Vigji che trascorrono pomeriggi molto divertenti cantando canzoni, giocando, raccontando barzellette e leggendo storie. Di volta in volta bussano alla porta simpatici ospiti, ognuno con una propria storia particolare: cantanti, scrittori, illustratori, insegnanti, maghi, cantautori, attori, comici, musicisti, cuochi e tanti altri. Ad arricchire ogni puntata tante rubriche: \u201cA ogni frut il so librut\u201d, dedicata alla lettura di un libro illustrato in lingua friulana; il \u201cZ\u00fbc\u201d, con le illustrazioni di \u201cAlc&amp;C\u00e8\u201d, inserto de \u201cLa Vita Cattolica\u201d; \u201cMaster Cogo Furlan\u201d, con la preparazione di facili piatti golosi; \u201c99 peraulis\u201d, le carte illustrate per imparare nuove parole in pi\u00f9 lingue; i \u201cM\u00fbts di d\u00ee\u201d e lo spazio dedicato ai video inviati dai bambini da casa. In chiusura, per gli adulti, una breve videointervista del progetto \u201cCressi cun plui lenghis\u201d per informare e sensibilizzare i genitori, i nonni e gli educatori sui vantaggi del plurilinguismo.<\/p>\n<p><strong>In questa puntata (1).<\/strong> Daria apre la prima puntata di Maman! raccontando chi \u00e8 e spiegando ai bambini come sar\u00e0 questa nuova trasmissione che avr\u00e0, ad ogni puntata, personaggi, giochi e rubriche divertenti. Sta aspettando Dario Zampa il suo primo ospite, uno dei cantautori storici del Friuli, con pi\u00f9 di 30 anni di carriera e 150.000 dischi venduti. Dario ha fatto anche il presentatore di diversi programmi in friulano su Telefriuli e Daria non vede l\u2019ora di incontrarlo. Quando arriva si scusa per il ritardo e racconta di essere appena rientrato dall\u2019Argentina dove \u00e8 andato a cantare per i friulani che abitano laggi\u00f9. A Maman! \u00e8 arrivato con la sua chitarra e, visto che si avvicinano le feste, lui e Daria cantano assieme la canzone del Natale. Dopo aver fatto il gioco di Alc&amp;C\u00e8, imparato qualche nuova parola con \u201c99 Peraulis\u201d, insegnato un nuovo modo di dire e apprezzato i video mandati da casa dai telespettatori di Maman!, Daria si rilassa in salotto con Vigji, il suo gattino, e gli racconta le avventure della giornata. In chiusura, per i genitori, va in onda una breve videointervista ad Antonella Sorace \u201cQuali sono i principali vantaggi del bilinguismo precoce?&#8221;<\/p>\n<p>Conduttrice e autrice: Daria Miani<br>\nRegia: Luca Fornasiero<br>\nMusica: Flaviano Miani<br>\nRedazione e consulenza linguistica ARLeF: Priscilla De Agostini, Linda Picco, Miriam Pupini<br>\nResponsabile del progetto per l\u2019ARLeF: William Cisilino<br>\nCoordinamento per l\u2019ARLeF: Priscilla De Agostini<br>\nSigla Maman!: voce e parole di Daria Miani, musica di Flaviano Miani, foto di Silvia Raber, animazione di Pierangelo Buttazzoni e Davide Nicolicchia<br>\nLogo Maman!: Calt Udine<br>\nDurata: 20 minuti circa<\/p>\n<p>Contatti:<br>\narlef@regione.fvg.it<br>\n<a href=\"mailto:maman@tvstar.com\">maman@tvstar.com<\/a><\/p>\n<\/div>\n","protected":false},"featured_media":3272,"menu_order":1,"template":"","series":[37,51],"class_list":["post-631","video","type-video","status-publish","has-post-thumbnail","hentry","series-lis-pontadis-di-maman-it","series-stagione-1-it"],"acf":{"url_video":"kBJ2fZAWOvM","anno":"","video_correlati":"","risorse_correlate":"","n_ordine":0},"_links":{"self":[{"href":"https:\/\/ghiti.it\/it\/wp-json\/wp\/v2\/video\/631"}],"collection":[{"href":"https:\/\/ghiti.it\/it\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/ghiti.it\/it\/wp-json\/wp\/v2\/types\/video"}],"version-history":[{"count":3,"href":"https:\/\/ghiti.it\/it\/wp-json\/wp\/v2\/video\/631\/revisions"}],"predecessor-version":[{"id":9240,"href":"https:\/\/ghiti.it\/it\/wp-json\/wp\/v2\/video\/631\/revisions\/9240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ghiti.it\/it\/wp-json\/wp\/v2\/media\/3272"}],"wp:attachment":[{"href":"https:\/\/ghiti.it\/it\/wp-json\/wp\/v2\/media?parent=631"}],"wp:term":[{"taxonomy":"series","embeddable":true,"href":"https:\/\/ghiti.it\/it\/wp-json\/wp\/v2\/series?post=631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}